{"id":16556,"date":"2022-10-19T11:28:13","date_gmt":"2022-10-19T11:28:13","guid":{"rendered":"https:\/\/vintagefrenchfinds.com\/?post_type=product&#038;p=16556"},"modified":"2025-03-17T16:06:09","modified_gmt":"2025-03-17T16:06:09","slug":"10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges","status":"publish","type":"product","link":"https:\/\/vintagefrenchfinds.com\/en\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges","title":{"rendered":"10 Antique French Limoges Porcelain Dessert Plates"},"content":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Joli lot de 10 assiettes \u00e0 dessert \/ fromage en porcelaine blanche orn\u00e9es de filet d\u2019or sur le pourtour et de d\u00e9tails fleuris.\\nElles sont estampill\u00e9es en dessous de : Limoges \u2013 FRANCE\\nLa porcelaine de Limoges est l\u2019une des deux principales productions porcelaini\u00e8res de France, et la seule issue d\u2019un v\u00e9ritable territoire de production, situ\u00e9e autour de la ville de Limoges dans les Hautes \u2013 Viennes.\\nC\u2019est en 1768 que l\u2019on trouva des gisements exploitables de kaolin mat\u00e9riau indispensable \u00e0 la production de cette c\u00e9ramique dure et translucide, et c\u2019est \u00e0 partir de cette d\u00e9couverte qu\u2019est n\u00e9e et s\u2019est d\u00e9velopp\u00e9e la porcelaine de Limoges.\\nDepuis le 18e si\u00e8cle, la notori\u00e9t\u00e9 de la porcelaine de Limoges s\u2019est d\u00e9velopp\u00e9e au point que le nom de la ville \u00e9voque imm\u00e9diatement l\u2019art de la porcelaine.\\nCes petits plats raffin\u00e9s rajouteront une touche chic \u00e0 votre table.\\nBon \u00e9tat, mais une des assiettes poss\u00e8de un petit \u00e9clat visible dans les photos\\nD 19 cm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15229,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:14}\">Joli lot de 10 assiettes \u00e0 dessert \/ fromage en porcelaine blanche orn\u00e9es de filet d\u2019or sur le pourtour et de d\u00e9tails fleuris.<br \/>\n<\/span><\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Joli lot de 10 assiettes \u00e0 dessert \/ fromage en porcelaine blanche orn\u00e9es de filet d\u2019or sur le pourtour et de d\u00e9tails fleuris.\\nElles sont estampill\u00e9es en dessous de : Limoges \u2013 FRANCE\\nLa porcelaine de Limoges est l\u2019une des deux principales productions porcelaini\u00e8res de France, et la seule issue d\u2019un v\u00e9ritable territoire de production, situ\u00e9e autour de la ville de Limoges dans les Hautes \u2013 Viennes.\\nC\u2019est en 1768 que l\u2019on trouva des gisements exploitables de kaolin mat\u00e9riau indispensable \u00e0 la production de cette c\u00e9ramique dure et translucide, et c\u2019est \u00e0 partir de cette d\u00e9couverte qu\u2019est n\u00e9e et s\u2019est d\u00e9velopp\u00e9e la porcelaine de Limoges.\\nDepuis le 18e si\u00e8cle, la notori\u00e9t\u00e9 de la porcelaine de Limoges s\u2019est d\u00e9velopp\u00e9e au point que le nom de la ville \u00e9voque imm\u00e9diatement l\u2019art de la porcelaine.\\nCes petits plats raffin\u00e9s rajouteront une touche chic \u00e0 votre table.\\nBon \u00e9tat, mais une des assiettes poss\u00e8de un petit \u00e9clat visible dans les photos\\nD 19 cm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15229,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:14}\">Elles sont estampill\u00e9es en dessous de : Limoges \u2013 FRANCE<br \/>\n<\/span><\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Joli lot de 10 assiettes \u00e0 dessert \/ fromage en porcelaine blanche orn\u00e9es de filet d\u2019or sur le pourtour et de d\u00e9tails fleuris.\\nElles sont estampill\u00e9es en dessous de : Limoges \u2013 FRANCE\\nLa porcelaine de Limoges est l\u2019une des deux principales productions porcelaini\u00e8res de France, et la seule issue d\u2019un v\u00e9ritable territoire de production, situ\u00e9e autour de la ville de Limoges dans les Hautes \u2013 Viennes.\\nC\u2019est en 1768 que l\u2019on trouva des gisements exploitables de kaolin mat\u00e9riau indispensable \u00e0 la production de cette c\u00e9ramique dure et translucide, et c\u2019est \u00e0 partir de cette d\u00e9couverte qu\u2019est n\u00e9e et s\u2019est d\u00e9velopp\u00e9e la porcelaine de Limoges.\\nDepuis le 18e si\u00e8cle, la notori\u00e9t\u00e9 de la porcelaine de Limoges s\u2019est d\u00e9velopp\u00e9e au point que le nom de la ville \u00e9voque imm\u00e9diatement l\u2019art de la porcelaine.\\nCes petits plats raffin\u00e9s rajouteront une touche chic \u00e0 votre table.\\nBon \u00e9tat, mais une des assiettes poss\u00e8de un petit \u00e9clat visible dans les photos\\nD 19 cm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15229,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:14}\">La porcelaine de Limoges est l\u2019une des deux principales productions porcelaini\u00e8res de France, et la seule issue d\u2019un v\u00e9ritable territoire de production, situ\u00e9e autour de la ville de Limoges dans les Hautes \u2013 Viennes.<br \/>\n<\/span><\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Joli lot de 10 assiettes \u00e0 dessert \/ fromage en porcelaine blanche orn\u00e9es de filet d\u2019or sur le pourtour et de d\u00e9tails fleuris.\\nElles sont estampill\u00e9es en dessous de : Limoges \u2013 FRANCE\\nLa porcelaine de Limoges est l\u2019une des deux principales productions porcelaini\u00e8res de France, et la seule issue d\u2019un v\u00e9ritable territoire de production, situ\u00e9e autour de la ville de Limoges dans les Hautes \u2013 Viennes.\\nC\u2019est en 1768 que l\u2019on trouva des gisements exploitables de kaolin mat\u00e9riau indispensable \u00e0 la production de cette c\u00e9ramique dure et translucide, et c\u2019est \u00e0 partir de cette d\u00e9couverte qu\u2019est n\u00e9e et s\u2019est d\u00e9velopp\u00e9e la porcelaine de Limoges.\\nDepuis le 18e si\u00e8cle, la notori\u00e9t\u00e9 de la porcelaine de Limoges s\u2019est d\u00e9velopp\u00e9e au point que le nom de la ville \u00e9voque imm\u00e9diatement l\u2019art de la porcelaine.\\nCes petits plats raffin\u00e9s rajouteront une touche chic \u00e0 votre table.\\nBon \u00e9tat, mais une des assiettes poss\u00e8de un petit \u00e9clat visible dans les photos\\nD 19 cm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15229,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:14}\">C\u2019est en 1768 que l\u2019on trouva des gisements exploitables de kaolin mat\u00e9riau indispensable \u00e0 la production de cette c\u00e9ramique dure et translucide, et c\u2019est \u00e0 partir de cette d\u00e9couverte qu\u2019est n\u00e9e et s\u2019est d\u00e9velopp\u00e9e la porcelaine de Limoges.<br \/>\n<\/span><\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Joli lot de 10 assiettes \u00e0 dessert \/ fromage en porcelaine blanche orn\u00e9es de filet d\u2019or sur le pourtour et de d\u00e9tails fleuris.\\nElles sont estampill\u00e9es en dessous de : Limoges \u2013 FRANCE\\nLa porcelaine de Limoges est l\u2019une des deux principales productions porcelaini\u00e8res de France, et la seule issue d\u2019un v\u00e9ritable territoire de production, situ\u00e9e autour de la ville de Limoges dans les Hautes \u2013 Viennes.\\nC\u2019est en 1768 que l\u2019on trouva des gisements exploitables de kaolin mat\u00e9riau indispensable \u00e0 la production de cette c\u00e9ramique dure et translucide, et c\u2019est \u00e0 partir de cette d\u00e9couverte qu\u2019est n\u00e9e et s\u2019est d\u00e9velopp\u00e9e la porcelaine de Limoges.\\nDepuis le 18e si\u00e8cle, la notori\u00e9t\u00e9 de la porcelaine de Limoges s\u2019est d\u00e9velopp\u00e9e au point que le nom de la ville \u00e9voque imm\u00e9diatement l\u2019art de la porcelaine.\\nCes petits plats raffin\u00e9s rajouteront une touche chic \u00e0 votre table.\\nBon \u00e9tat, mais une des assiettes poss\u00e8de un petit \u00e9clat visible dans les photos\\nD 19 cm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15229,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:14}\">Depuis le 18e si\u00e8cle, la notori\u00e9t\u00e9 de la porcelaine de Limoges s\u2019est d\u00e9velopp\u00e9e au point que le nom de la ville \u00e9voque imm\u00e9diatement l\u2019art de la porcelaine.<br \/>\n<\/span><\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Joli lot de 10 assiettes \u00e0 dessert \/ fromage en porcelaine blanche orn\u00e9es de filet d\u2019or sur le pourtour et de d\u00e9tails fleuris.\\nElles sont estampill\u00e9es en dessous de : Limoges \u2013 FRANCE\\nLa porcelaine de Limoges est l\u2019une des deux principales productions porcelaini\u00e8res de France, et la seule issue d\u2019un v\u00e9ritable territoire de production, situ\u00e9e autour de la ville de Limoges dans les Hautes \u2013 Viennes.\\nC\u2019est en 1768 que l\u2019on trouva des gisements exploitables de kaolin mat\u00e9riau indispensable \u00e0 la production de cette c\u00e9ramique dure et translucide, et c\u2019est \u00e0 partir de cette d\u00e9couverte qu\u2019est n\u00e9e et s\u2019est d\u00e9velopp\u00e9e la porcelaine de Limoges.\\nDepuis le 18e si\u00e8cle, la notori\u00e9t\u00e9 de la porcelaine de Limoges s\u2019est d\u00e9velopp\u00e9e au point que le nom de la ville \u00e9voque imm\u00e9diatement l\u2019art de la porcelaine.\\nCes petits plats raffin\u00e9s rajouteront une touche chic \u00e0 votre table.\\nBon \u00e9tat, mais une des assiettes poss\u00e8de un petit \u00e9clat visible dans les photos\\nD 19 cm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15229,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:14}\">Ces petits plats raffin\u00e9s rajouteront une touche chic \u00e0 votre table.<br \/>\n<\/span><\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Joli lot de 10 assiettes \u00e0 dessert \/ fromage en porcelaine blanche orn\u00e9es de filet d\u2019or sur le pourtour et de d\u00e9tails fleuris.\\nElles sont estampill\u00e9es en dessous de : Limoges \u2013 FRANCE\\nLa porcelaine de Limoges est l\u2019une des deux principales productions porcelaini\u00e8res de France, et la seule issue d\u2019un v\u00e9ritable territoire de production, situ\u00e9e autour de la ville de Limoges dans les Hautes \u2013 Viennes.\\nC\u2019est en 1768 que l\u2019on trouva des gisements exploitables de kaolin mat\u00e9riau indispensable \u00e0 la production de cette c\u00e9ramique dure et translucide, et c\u2019est \u00e0 partir de cette d\u00e9couverte qu\u2019est n\u00e9e et s\u2019est d\u00e9velopp\u00e9e la porcelaine de Limoges.\\nDepuis le 18e si\u00e8cle, la notori\u00e9t\u00e9 de la porcelaine de Limoges s\u2019est d\u00e9velopp\u00e9e au point que le nom de la ville \u00e9voque imm\u00e9diatement l\u2019art de la porcelaine.\\nCes petits plats raffin\u00e9s rajouteront une touche chic \u00e0 votre table.\\nBon \u00e9tat, mais une des assiettes poss\u00e8de un petit \u00e9clat visible dans les photos\\nD 19 cm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15229,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:14}\">Bon \u00e9tat, mais une des assiettes poss\u00e8de un petit \u00e9clat visible dans les photos<br \/>\n<\/span><\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Joli lot de 10 assiettes \u00e0 dessert \/ fromage en porcelaine blanche orn\u00e9es de filet d\u2019or sur le pourtour et de d\u00e9tails fleuris.\\nElles sont estampill\u00e9es en dessous de : Limoges \u2013 FRANCE\\nLa porcelaine de Limoges est l\u2019une des deux principales productions porcelaini\u00e8res de France, et la seule issue d\u2019un v\u00e9ritable territoire de production, situ\u00e9e autour de la ville de Limoges dans les Hautes \u2013 Viennes.\\nC\u2019est en 1768 que l\u2019on trouva des gisements exploitables de kaolin mat\u00e9riau indispensable \u00e0 la production de cette c\u00e9ramique dure et translucide, et c\u2019est \u00e0 partir de cette d\u00e9couverte qu\u2019est n\u00e9e et s\u2019est d\u00e9velopp\u00e9e la porcelaine de Limoges.\\nDepuis le 18e si\u00e8cle, la notori\u00e9t\u00e9 de la porcelaine de Limoges s\u2019est d\u00e9velopp\u00e9e au point que le nom de la ville \u00e9voque imm\u00e9diatement l\u2019art de la porcelaine.\\nCes petits plats raffin\u00e9s rajouteront une touche chic \u00e0 votre table.\\nBon \u00e9tat, mais une des assiettes poss\u00e8de un petit \u00e9clat visible dans les photos\\nD 19 cm&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:15229,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:14}\">D 19 cm<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joli lot de 10 assiettes \u00e0 dessert \/ fromage en porcelaine blanche orn\u00e9es de filet d\u2019or sur le pourtour et de d\u00e9tails fleuris. Elles sont estampill\u00e9es en dessous de : Limoges \u2013 FRANCE La porcelaine de Limoges est l\u2019une des deux principales productions porcelaini\u00e8res de France, et la seule issue d\u2019un v\u00e9ritable territoire de production, [&hellip;]<\/p>\n","protected":false},"featured_media":16557,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[3542,3546],"product_tag":[1197,1115,1845,1501,1229,1920,1380,1211,1021,1011],"class_list":["post-16556","product","type-product","status-publish","has-post-thumbnail","product_cat-art-de-la-table","product_cat-assiettes-a-dessert-a-fromage","product_tag-ancien","product_tag-art-de-la-table","product_tag-assiettes","product_tag-assiettes-a-dessert","product_tag-assiette-a-fromage","product_tag-cuisine","product_tag-limoges","product_tag-porcelaine","product_tag-porcelaine-de-limoges","product_tag-vintage","desktop-align-left","tablet-align-left","mobile-align-left","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>10 Anciennes Assiettes \u00e0 Dessert en Porcelaine de Limoges - Vintage French Finds<\/title>\n<meta name=\"description\" content=\"The best of French vintage delivered to your doorstep direct from France : fashion, furniture, decoration, table art, curiosities, collections and art work.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vintagefrenchfinds.com\/en\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 Anciennes Assiettes \u00e0 Dessert en Porcelaine de Limoges - Vintage French Finds\" \/>\n<meta property=\"og:description\" content=\"The best of French vintage delivered to your doorstep direct from France : fashion, furniture, decoration, table art, curiosities, collections and art work.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vintagefrenchfinds.com\/en\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges\/\" \/>\n<meta property=\"og:site_name\" content=\"Vintage French Finds\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-17T16:06:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vintagefrenchfinds.com\/wp-content\/uploads\/2022\/10\/DSCN6816.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"886\" \/>\n\t<meta property=\"og:image:height\" content=\"686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/product\\\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges\",\"url\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/product\\\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges\",\"name\":\"10 Anciennes Assiettes \u00e0 Dessert en Porcelaine de Limoges - Vintage French Finds\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/product\\\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/product\\\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSCN6816.jpg\",\"datePublished\":\"2022-10-19T11:28:13+00:00\",\"dateModified\":\"2025-03-17T16:06:09+00:00\",\"description\":\"The best of French vintage delivered to your doorstep direct from France : fashion, furniture, decoration, table art, curiosities, collections and art work.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/product\\\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vintagefrenchfinds.com\\\/product\\\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/product\\\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges#primaryimage\",\"url\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSCN6816.jpg\",\"contentUrl\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/DSCN6816.jpg\",\"width\":886,\"height\":686,\"caption\":\"11 Assiettes \u00e0 Feomage Vintage en Porcelaine de Limoges\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/product\\\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BOUTIQUE\",\"item\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/shop\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"10 Anciennes Assiettes \u00e0 Dessert en Porcelaine de Limoges\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/#website\",\"url\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/\",\"name\":\"Vintage French Finds\",\"description\":\"The best of French vintage delivered to your doorstep direct from France : fashion, furniture, decoration, table art, curiosities, collections and art work.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vintagefrenchfinds.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"10 Anciennes Assiettes \u00e0 Dessert en Porcelaine de Limoges - Vintage French Finds","description":"The best of French vintage delivered to your doorstep direct from France : fashion, furniture, decoration, table art, curiosities, collections and art work.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vintagefrenchfinds.com\/en\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges\/","og_locale":"en_GB","og_type":"article","og_title":"10 Anciennes Assiettes \u00e0 Dessert en Porcelaine de Limoges - Vintage French Finds","og_description":"The best of French vintage delivered to your doorstep direct from France : fashion, furniture, decoration, table art, curiosities, collections and art work.","og_url":"https:\/\/vintagefrenchfinds.com\/en\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges\/","og_site_name":"Vintage French Finds","article_modified_time":"2025-03-17T16:06:09+00:00","og_image":[{"width":886,"height":686,"url":"https:\/\/vintagefrenchfinds.com\/wp-content\/uploads\/2022\/10\/DSCN6816.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vintagefrenchfinds.com\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges","url":"https:\/\/vintagefrenchfinds.com\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges","name":"10 Anciennes Assiettes \u00e0 Dessert en Porcelaine de Limoges - Vintage French Finds","isPartOf":{"@id":"https:\/\/vintagefrenchfinds.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vintagefrenchfinds.com\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges#primaryimage"},"image":{"@id":"https:\/\/vintagefrenchfinds.com\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges#primaryimage"},"thumbnailUrl":"https:\/\/vintagefrenchfinds.com\/wp-content\/uploads\/2022\/10\/DSCN6816.jpg","datePublished":"2022-10-19T11:28:13+00:00","dateModified":"2025-03-17T16:06:09+00:00","description":"The best of French vintage delivered to your doorstep direct from France : fashion, furniture, decoration, table art, curiosities, collections and art work.","breadcrumb":{"@id":"https:\/\/vintagefrenchfinds.com\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vintagefrenchfinds.com\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/vintagefrenchfinds.com\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges#primaryimage","url":"https:\/\/vintagefrenchfinds.com\/wp-content\/uploads\/2022\/10\/DSCN6816.jpg","contentUrl":"https:\/\/vintagefrenchfinds.com\/wp-content\/uploads\/2022\/10\/DSCN6816.jpg","width":886,"height":686,"caption":"11 Assiettes \u00e0 Feomage Vintage en Porcelaine de Limoges"},{"@type":"BreadcrumbList","@id":"https:\/\/vintagefrenchfinds.com\/product\/10-anciennes-assiettes-a-dessert-en-porcelaine-de-limoges#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vintagefrenchfinds.com\/"},{"@type":"ListItem","position":2,"name":"BOUTIQUE","item":"https:\/\/vintagefrenchfinds.com\/shop"},{"@type":"ListItem","position":3,"name":"10 Anciennes Assiettes \u00e0 Dessert en Porcelaine de Limoges"}]},{"@type":"WebSite","@id":"https:\/\/vintagefrenchfinds.com\/#website","url":"https:\/\/vintagefrenchfinds.com\/","name":"Vintage French Finds\u00a0","description":"The best of French vintage delivered to your doorstep direct from France : fashion, furniture, decoration, table art, curiosities, collections and art work.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vintagefrenchfinds.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"jetpack_sharing_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/vintagefrenchfinds.com\/en\/wp-json\/wp\/v2\/product\/16556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vintagefrenchfinds.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/vintagefrenchfinds.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vintagefrenchfinds.com\/en\/wp-json\/wp\/v2\/media\/16557"}],"wp:attachment":[{"href":"https:\/\/vintagefrenchfinds.com\/en\/wp-json\/wp\/v2\/media?parent=16556"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/vintagefrenchfinds.com\/en\/wp-json\/wp\/v2\/product_brand?post=16556"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/vintagefrenchfinds.com\/en\/wp-json\/wp\/v2\/product_cat?post=16556"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/vintagefrenchfinds.com\/en\/wp-json\/wp\/v2\/product_tag?post=16556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}